{"id":48,"date":"2024-08-29T09:48:09","date_gmt":"2024-08-29T09:48:09","guid":{"rendered":"https:\/\/psona.io\/?page_id=48"},"modified":"2026-01-05T18:32:19","modified_gmt":"2026-01-05T18:32:19","slug":"passer-le-test","status":"publish","type":"page","link":"https:\/\/psona.io\/es\/passer-le-test\/","title":{"rendered":"Haz la prueba"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Header&#8221; module_id=&#8221;custom-header&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f1f5eb&#8221; background_image=&#8221;https:\/\/psona.io\/wp-content\/uploads\/2024\/09\/BG_TEST.svg&#8221; positioning=&#8221;none&#8221; height=&#8221;100vh&#8221; height_tablet=&#8221;auto&#8221; height_phone=&#8221;auto&#8221; height_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;10px||0px||false|false&#8221; background_last_edited=&#8221;on|tablet&#8221; background_image_tablet=&#8221;https:\/\/psona.io\/wp-content\/uploads\/2024\/09\/Ellipse-64.svg&#8221; background_enable_image_tablet=&#8221;on&#8221; background_enable_image_phone=&#8221;off&#8221; background_size_tablet=&#8221;contain&#8221; background_size_phone=&#8221;initial&#8221; background_image_width_tablet=&#8221;1000px&#8221; background_image_width_phone=&#8221;200px&#8221; background_position_tablet=&#8221;bottom_center&#8221; background_position_phone=&#8221;bottom_center&#8221; background_vertical_offset_tablet=&#8221;-40vh&#8221; background_vertical_offset_phone=&#8221;-100vh&#8221; z_index_tablet=&#8221;&#8221; z_index_phone=&#8221;2&#8243; z_index_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221; custom_css_before_last_edited=&#8221;on|phone&#8221; custom_css_after_last_edited=&#8221;on|desktop&#8221;][et_pb_row _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; position_origin_a=&#8221;top_center&#8221; vertical_offset=&#8221;0px&#8221; vertical_offset_tablet=&#8221;0px&#8221; vertical_offset_phone=&#8221;0px&#8221; vertical_offset_last_edited=&#8221;on|desktop&#8221; width=&#8221;90%&#8221; width_tablet=&#8221;20%&#8221; width_phone=&#8221;30%&#8221; width_last_edited=&#8221;on|tablet&#8221; custom_margin=&#8221;30px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/psona.io\/wp-content\/uploads\/2024\/08\/Logotype_vert1.svg&#8221; title_text=&#8221;Logotype_vert1&#8243; url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoiaG9tZV91cmwiLCJzZXR0aW5ncyI6e319@&#8221; _builder_version=&#8221;4.27.0&#8243; _dynamic_attributes=&#8221;url&#8221; _module_preset=&#8221;default&#8221; height=&#8221;100px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row module_class=&#8221;title-section&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; vertical_offset=&#8221;0px&#8221; custom_margin=&#8221;20px||||false|false&#8221; custom_margin_tablet=&#8221;20px||||false|false&#8221; custom_margin_phone=&#8221;20px||||false|false&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text module_class=&#8221;custom-title&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#034833&#8243; header_font_size=&#8221;90px&#8221; header_font_size_phone=&#8221;30px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Test de personalidad<\/h1>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_text_color=&#8221;#949494&#8243; text_font_size=&#8221;20px&#8221; text_orientation=&#8221;center&#8221; width=&#8221;55%&#8221; width_tablet=&#8221;55%&#8221; width_phone=&#8221;100%&#8221; width_last_edited=&#8221;on|phone&#8221; module_alignment=&#8221;center&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;|0px||0px|false|true&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;|0px||0px|false|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; text_font_size_tablet=&#8221;18px&#8221; text_font_size_phone=&#8221;12px&#8221; text_font_size_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Su personalidad es tan \u00fanica como usted. Realiza nuestro exclusivo test de personalidad para vivir una experiencia introspectiva cautivadora.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; disabled_on=&#8221;on|on|off&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;45%&#8221; width_tablet=&#8221;55%&#8221; width_phone=&#8221;55%&#8221; width_last_edited=&#8221;on|tablet&#8221; min_height=&#8221;300px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;30px||||false|false&#8221; global_colors_info=&#8221;{}&#8221; custom_css_main_element_last_edited=&#8221;on|tablet&#8221; custom_css_main_element_tablet=&#8221;display:flex;||flex-direction:row;||justify-content:center;||align-items:center;&#8221; custom_css_main_element_phone=&#8221;display:flex;||flex-direction:row;||justify-content:center;||align-items:center;&#8221;][et_pb_image src=&#8221;https:\/\/psona.io\/wp-content\/uploads\/2024\/09\/time_cion.svg&#8221; title_text=&#8221;time_cion&#8221; show_bottom_space=&#8221;off&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; width_tablet=&#8221;100px&#8221; width_phone=&#8221;100px&#8221; width_last_edited=&#8221;on|tablet&#8221; custom_margin=&#8221;0px||||false|false&#8221; custom_margin_tablet=&#8221;0px|30px|||false|false&#8221; custom_margin_phone=&#8221;0px|30px|||false|false&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; custom_padding=&#8221;0px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#000000&#8243; header_4_font=&#8221;|700|||||||&#8221; header_4_text_align=&#8221;center&#8221; header_4_text_color=&#8221;#034833&#8243; header_4_font_size=&#8221;20px&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;0px||||false|false&#8221; custom_padding=&#8221;0px||||false|false&#8221; header_4_text_align_tablet=&#8221;left&#8221; header_4_text_align_phone=&#8221;left&#8221; header_4_text_align_last_edited=&#8221;on|desktop&#8221; text_orientation_tablet=&#8221;left&#8221; text_orientation_phone=&#8221;left&#8221; text_orientation_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4>-10 minutos<\/h4>\n<p>Nuestra prueba dura menos<br \/>de 10 minutos<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221; custom_css_main_element_last_edited=&#8221;on|tablet&#8221; custom_css_main_element_tablet=&#8221;display:flex;||flex-direction:row;||justify-content:center;||align-items:center;&#8221; custom_css_main_element_phone=&#8221;display:flex;||flex-direction:row;||justify-content:center;||align-items:center;&#8221;][et_pb_image src=&#8221;https:\/\/psona.io\/wp-content\/uploads\/2024\/09\/chat_icon.svg&#8221; title_text=&#8221;chat_icon&#8221; show_bottom_space=&#8221;off&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; width_tablet=&#8221;100px&#8221; width_phone=&#8221;100px&#8221; width_last_edited=&#8221;on|tablet&#8221; custom_margin=&#8221;0px||||false|false&#8221; custom_margin_tablet=&#8221;0px|30px|||false|false&#8221; custom_margin_phone=&#8221;0px|30px|||false|false&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; custom_padding=&#8221;0px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#000000&#8243; header_4_font=&#8221;|700|||||||&#8221; header_4_text_align=&#8221;center&#8221; header_4_text_color=&#8221;#034833&#8243; header_4_font_size=&#8221;20px&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;0px||||false|false&#8221; custom_padding=&#8221;0px||||false|false&#8221; header_4_text_align_tablet=&#8221;left&#8221; header_4_text_align_phone=&#8221;left&#8221; header_4_text_align_last_edited=&#8221;on|desktop&#8221; text_orientation_tablet=&#8221;left&#8221; text_orientation_phone=&#8221;left&#8221; text_orientation_last_edited=&#8221;on|tablet&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4>Honestidad<\/h4>\n<p>Tienes que responder con sinceridad (aunque no te gusten las respuestas).<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;30px||||false|false&#8221; global_colors_info=&#8221;{}&#8221; custom_css_main_element_last_edited=&#8221;on|tablet&#8221; custom_css_main_element_tablet=&#8221;display:flex;||flex-direction:row;||justify-content:center;||align-items:center;&#8221; custom_css_main_element_phone=&#8221;display:flex;||flex-direction:row;||justify-content:center;||align-items:center;&#8221;][et_pb_image src=&#8221;https:\/\/psona.io\/wp-content\/uploads\/2024\/09\/check_icon.svg&#8221; title_text=&#8221;check_icon&#8221; show_bottom_space=&#8221;off&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; width_tablet=&#8221;100px&#8221; width_phone=&#8221;100px&#8221; width_last_edited=&#8221;on|tablet&#8221; custom_margin=&#8221;0px||||false|false&#8221; custom_margin_tablet=&#8221;0px|30px|||false|false&#8221; custom_margin_phone=&#8221;0px|30px|||false|false&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; custom_padding=&#8221;0px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#000000&#8243; header_4_font=&#8221;|700|||||||&#8221; header_4_text_align=&#8221;center&#8221; header_4_text_color=&#8221;#034833&#8243; header_4_font_size=&#8221;20px&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;0px||||false|false&#8221; custom_padding=&#8221;0px||||false|false&#8221; header_4_text_align_tablet=&#8221;left&#8221; header_4_text_align_phone=&#8221;left&#8221; header_4_text_align_last_edited=&#8221;on|desktop&#8221; text_orientation_tablet=&#8221;left&#8221; text_orientation_phone=&#8221;left&#8221; text_orientation_last_edited=&#8221;on|tablet&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><span>No neutral<\/span><\/h4>\n<p>Intenta no dejar respuestas neutras.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row disabled_on=&#8221;off|off|on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;45%&#8221; width_tablet=&#8221;55%&#8221; width_phone=&#8221;85%&#8221; width_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;30px||||false|false&#8221; global_colors_info=&#8221;{}&#8221; custom_css_main_element_last_edited=&#8221;on|tablet&#8221;][et_pb_text content_tablet=&#8221;<\/p>\n<h4><img src=\"%22https:\/\/psona.io\/wp-content\/uploads\/2024\/09\/time_cion.svg%22\" width=\"%22100%22\" height=\"%22100%22\" alt=\"%22%22\" class=\"%22wp-image-4574\" alignnone size-thumbnail%22 style=\"%22float:\" left; margin-right: 20px;%22 \/><\/h4>\n<h4><\/h4>\n<h4>-10 minutos<\/h4>\n<p><span>Nuestra prueba dura menos de 10 minutos<\/span><\/p>\n<\/p>\n<p>&#8221; content_phone=&#8221;<\/p>\n<div class=\"%22wrap-img%22\"><img src=\"%22https:\/\/psona.io\/wp-content\/uploads\/2024\/09\/time_cion.svg%22\" width=\"%2255%22\" height=\"%2255%22\" alt=\"%22%22\" class=\"%22wp-image-4575\" alignnone size-thumbnail%22 style=\"%22float:\" left; margin-right: 20px;%22 \/><\/div>\n<div class=\"%22content-text%22\">\n<h4>-10 minutos<\/h4>\n<p><span>Nuestra prueba dura menos de 10 minutos<\/span><\/p>\n<\/div>\n<p>&#8221; content_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#000000&#8243; header_4_font=&#8221;|700|||||||&#8221; header_4_text_align=&#8221;center&#8221; header_4_text_color=&#8221;#034833&#8243; header_4_font_size=&#8221;20px&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;0px||||false|false&#8221; custom_padding=&#8221;0px||||false|false&#8221; text_font_size_tablet=&#8221;16px&#8221; text_font_size_phone=&#8221;12px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; header_4_text_align_tablet=&#8221;left&#8221; header_4_text_align_phone=&#8221;left&#8221; header_4_text_align_last_edited=&#8221;on|tablet&#8221; header_4_font_size_tablet=&#8221;20px&#8221; header_4_font_size_phone=&#8221;14px&#8221; header_4_font_size_last_edited=&#8221;on|phone&#8221; text_orientation_tablet=&#8221;left&#8221; text_orientation_phone=&#8221;left&#8221; text_orientation_last_edited=&#8221;on|tablet&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; custom_css_main_element_last_edited=&#8221;on|phone&#8221;]<\/p>\n<h4><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/psona.io\/wp-content\/uploads\/2024\/09\/time_cion.svg\" width=\"100\" height=\"100\" alt=\"\" class=\"wp-image-4574 alignnone size-thumbnail\" style=\"float: left; margin-right: 20px;\" \/><\/h4>\n<h4><\/h4>\n<h4>-10 minutos<\/h4>\n<p><span>Nuestra prueba dura menos de 10 minutos<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][et_pb_text content_tablet=&#8221;<\/p>\n<h4><img src=\"%22https:\/\/psona.io\/wp-content\/uploads\/2024\/09\/chat_icon.svg%22\" width=\"%22100%22\" height=\"%22100%22\" alt=\"%22%22\" class=\"%22wp-image-4574\" alignnone size-thumbnail%22 style=\"%22float:\" left; margin-right: 20px;%22 \/><\/h4>\n<h4><\/h4>\n<h4>Honestidad<\/h4>\n<p>Tienes que responder con sinceridad (aunque no te gusten las respuestas).<\/p>\n<\/p>\n<p>&#8221; content_phone=&#8221;<\/p>\n<div class=\"%22wrap-img%22\">\n<h4><img src=\"%22https:\/\/psona.io\/wp-content\/uploads\/2024\/09\/chat_icon.svg%22\" width=\"%2255%22\" height=\"%2255%22\" alt=\"%22%22\" class=\"%22wp-image-4574\" alignnone size-thumbnail%22 style=\"%22float:\" left; margin-right: 20px;%22 \/><\/h4>\n<h4><\/h4>\n<h4>Honestidad<\/h4>\n<p>Vous devez r\u00e9pondre honn\u00eatement.<\/p>\n<\/p>\n<\/div>\n<p>&#8221; content_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#000000&#8243; header_4_font=&#8221;|700|||||||&#8221; header_4_text_align=&#8221;center&#8221; header_4_text_color=&#8221;#034833&#8243; header_4_font_size=&#8221;20px&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; text_font_size_tablet=&#8221;16px&#8221; text_font_size_phone=&#8221;12px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; header_4_text_align_tablet=&#8221;left&#8221; header_4_text_align_phone=&#8221;left&#8221; header_4_text_align_last_edited=&#8221;on|tablet&#8221; header_4_font_size_tablet=&#8221;20px&#8221; header_4_font_size_phone=&#8221;14px&#8221; header_4_font_size_last_edited=&#8221;on|phone&#8221; text_orientation_tablet=&#8221;left&#8221; text_orientation_phone=&#8221;left&#8221; text_orientation_last_edited=&#8221;on|tablet&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/psona.io\/wp-content\/uploads\/2024\/09\/chat_icon.svg\" width=\"100\" height=\"100\" alt=\"\" class=\"wp-image-4574 alignnone size-thumbnail\" style=\"float: left; margin-right: 20px;\" \/><\/h4>\n<h4><\/h4>\n<h4>Honestidad<\/h4>\n<p>Tienes que responder con sinceridad (aunque no te gusten las respuestas).<\/p>\n<p>&nbsp;[\/et_pb_text][et_pb_text content_tablet=&#8221;<\/p>\n<h4><img src=\"%22https:\/\/psona.io\/wp-content\/uploads\/2024\/09\/check_icon.svg%22\" width=\"%22100%22\" height=\"%22100%22\" alt=\"%22%22\" class=\"%22wp-image-4574\" alignnone size-thumbnail%22 style=\"%22float:\" left; margin-right: 20px;%22 \/><\/h4>\n<h4><\/h4>\n<h4>No neutral<\/h4>\n<p>Intenta no dejar respuestas neutras.<\/p>\n<\/p>\n<p>&#8221; content_phone=&#8221;<\/p>\n<h4><img src=\"%22https:\/\/psona.io\/wp-content\/uploads\/2024\/09\/check_icon.svg%22\" width=\"%2255%22\" height=\"%2255%22\" alt=\"%22%22\" class=\"%22wp-image-4574\" alignnone size-thumbnail%22 style=\"%22float:\" left; margin-right: 20px;%22 \/><\/h4>\n<h4><\/h4>\n<h4>No neutral<\/h4>\n<p>Intenta no dejar respuestas neutras.<\/p>\n<p> &#8221; content_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#000000&#8243; header_4_font=&#8221;|700|||||||&#8221; header_4_text_align=&#8221;center&#8221; header_4_text_color=&#8221;#034833&#8243; header_4_font_size=&#8221;20px&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;0px||||false|false&#8221; custom_padding=&#8221;0px||||false|false&#8221; text_font_size_tablet=&#8221;16px&#8221; text_font_size_phone=&#8221;12px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; header_4_text_align_tablet=&#8221;left&#8221; header_4_text_align_phone=&#8221;left&#8221; header_4_text_align_last_edited=&#8221;on|tablet&#8221; header_4_font_size_tablet=&#8221;20px&#8221; header_4_font_size_phone=&#8221;14px&#8221; header_4_font_size_last_edited=&#8221;on|phone&#8221; text_orientation_tablet=&#8221;left&#8221; text_orientation_phone=&#8221;left&#8221; text_orientation_last_edited=&#8221;on|tablet&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/psona.io\/wp-content\/uploads\/2024\/09\/check_icon.svg\" width=\"100\" height=\"100\" alt=\"\" class=\"wp-image-4574 alignnone size-thumbnail\" style=\"float: left; margin-right: 20px;\" \/><\/h4>\n<h4><\/h4>\n<h4>No neutral<\/h4>\n<p>Intenta no dejar respuestas neutras.<\/p>\n<p>&nbsp;[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; vertical_offset=&#8221;0px&#8221; width_tablet=&#8221;&#8221; width_phone=&#8221;&#8221; width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;20px||0px||false|false&#8221; custom_margin_tablet=&#8221;20px||||false|false&#8221; custom_margin_phone=&#8221;20px||||false|false&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_button button_url=&#8221;#&#8221; button_text=&#8221;Passer le test&#8221; button_alignment=&#8221;center&#8221; button_alignment_tablet=&#8221;center&#8221; button_alignment_phone=&#8221;center&#8221; button_alignment_last_edited=&#8221;on|tablet&#8221; module_id=&#8221;start-quizz&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; button_text_size=&#8221;25px&#8221; button_bg_color=&#8221;#83cd20&#8243; button_border_width=&#8221;0px&#8221; button_border_color=&#8221;RGBA(255,255,255,0)&#8221; custom_padding=&#8221;15px|100px|15px|50px|true|false&#8221; custom_padding_tablet=&#8221;20px|40px|20px|40px|true|true&#8221; custom_padding_phone=&#8221;20px|40px|20px|40px|true|true&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; button_text_size_tablet=&#8221;20px&#8221; button_text_size_phone=&#8221;20px&#8221; button_text_size_last_edited=&#8221;on|tablet&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; button_bg_color__hover_enabled=&#8221;on|hover&#8221; button_bg_enable_color__hover=&#8221;on&#8221; button_bg_color__hover=&#8221;#53a018&#8243;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;JS&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; positioning=&#8221;absolute&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<script><!-- [et_pb_line_break_holder] -->\/\/ jQUERY<!-- [et_pb_line_break_holder] -->$(document).ready(function() {<!-- [et_pb_line_break_holder] -->    $('#b5pt-timer').appendTo('#new-timer');<!-- [et_pb_line_break_holder] -->    $('.simpay-checkout-btn-container').after('<\/p>\n<div class=\"secure-payment\">\n<div class=\"img-wrap\"><img decoding=\"async\" src=\"https:\/\/psona.io\/wp-content\/uploads\/2024\/09\/Groupe-97.svg\" alt=\"secure-payment\"><\/div>\n<div class=\"text-wrap\"><pee>All transactions are secure and encrypted. Credit card information is never stored on the website.<\/pee><\/div>\n<\/div>\n<p>');<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] -->\/\/ Animate switch page<!-- [et_pb_line_break_holder] -->\/\/ On click #start-quizz button, slide to #custom-test<!-- [et_pb_line_break_holder] -->$('#start-quizz').click(function(e) {<!-- [et_pb_line_break_holder] -->  e.preventDefault();<!-- [et_pb_line_break_holder] -->    \/\/ Slide to #custom-test<!-- [et_pb_line_break_holder] -->    $('#custom-test').show();<!-- [et_pb_line_break_holder] -->  $('#custom-header').attr(\"style\", \"display: none !important\");<!-- [et_pb_line_break_holder] -->});<!-- [et_pb_line_break_holder] -->    <!-- [et_pb_line_break_holder] -->});<!-- [et_pb_line_break_holder] --><\/script>[\/et_pb_code][et_pb_code admin_label=&#8221;Code HIPAY&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<script><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->\/\/ jQUERY<!-- [et_pb_line_break_holder] -->$(document).ready(function() {<!-- [et_pb_line_break_holder] -->  $(\"#result-button\").click(function () {<!-- [et_pb_line_break_holder] -->    $('#payment-form').show();<!-- [et_pb_line_break_holder] -->     $(\"iframe\").each(function () {<!-- [et_pb_line_break_holder] -->                \/\/ add class<!-- [et_pb_line_break_holder] -->                $(this).addClass(\"iframe-display\");<!-- [et_pb_line_break_holder] -->              });<!-- [et_pb_line_break_holder] -->    $('#iframe-hipay-parent').show();<!-- [et_pb_line_break_holder] -->  });<!-- [et_pb_line_break_holder] -->   <!-- [et_pb_line_break_holder] -->});<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><\/script>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Quizz&#8221; module_id=&#8221;custom-test&#8221; _builder_version=&#8221;4.27.0&#8243; background_color=&#8221;#f1f5eb&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;15px||0px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; custom_css_before_last_edited=&#8221;on|desktop&#8221; custom_css_after_last_edited=&#8221;on|phone&#8221;][et_pb_row column_structure=&#8221;1_4,3_4&#8243; module_class=&#8221;row-progress&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; width_tablet=&#8221;55%&#8221; width_phone=&#8221;90%&#8221; width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; custom_css_main_element=&#8221;display:flex;||align-items:center;&#8221; global_colors_info=&#8221;{}&#8221; custom_css_main_element_last_edited=&#8221;on|phone&#8221; custom_css_main_element_phone=&#8221;display:flex;||flex-direction:column;||align-items:center;&#8221; custom_css_main_element_tablet=&#8221;display:flex;||align-items:center;&#8221;][et_pb_column type=&#8221;1_4&#8243; module_class=&#8221;col-logo&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; custom_css_main_element=&#8221;width:12% !important;&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/psona.io\/wp-content\/uploads\/2024\/08\/Logotype_vert1.svg&#8221; title_text=&#8221;Logotype_vert1&#8243; url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoiaG9tZV91cmwiLCJzZXR0aW5ncyI6e319@&#8221; align_tablet=&#8221;&#8221; align_phone=&#8221;center&#8221; align_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.0&#8243; _dynamic_attributes=&#8221;url&#8221; _module_preset=&#8221;default&#8221; width_tablet=&#8221;100%&#8221; width_phone=&#8221;40%&#8221; width_last_edited=&#8221;on|phone&#8221; height=&#8221;100px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_4&#8243; module_class=&#8221;col-timer&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; custom_css_main_element=&#8221;width:45% !important;||margin-left:10% !important;&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_orientation=&#8221;center&#8221; module_alignment=&#8221;center&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<div id=\"b5pt_form_progressbar\">\n<div class=\"pb_inner\"><\/div>\n<\/div>\n<p>[\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row module_class=&#8221;row-timer&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; position_origin_a=&#8221;top_center&#8221; width=&#8221;30%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Timer&#8221; module_id=&#8221;new-timer&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; background_image=&#8221;https:\/\/psona.io\/wp-content\/uploads\/2024\/09\/timer_bg.svg&#8221; background_size=&#8221;contain&#8221; text_orientation=&#8221;center&#8221; width=&#8221;100%&#8221; height=&#8221;100px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8221;row&#8221; _builder_version=&#8221;4.21.0&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; width=&#8221;90%&#8221; max_width=&#8221;1500px&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Text&#8221; _builder_version=&#8221;4.27.4&#8243; background_color=&#8221;RGBA(255,255,255,0)&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<div id=\"b5pt-timer\">00:00<\/div>\r\n<form id=\"b5pt_form\" action=\"\">\r\n\r\n<input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form>\r\n\r\n<div id=\"payment-secure-modal\" class=\"payment-secure-background\" style=\"display : none;\">\r\n    <div id=\"payment-secure\" class=\"payment-secure\">\r\n        <svg onclick=\"document.getElementById('payment-secure-modal').style.display = 'none';\"\r\n            xmlns=\"https:\/\/www.w3.org\/2000\/svg\" fill=\"none\" viewbox=\"0 0 24 24\" stroke-width=\"1.5\" stroke=\"currentColor\"\r\n            class=\"close-icon-secure\">\r\n            <path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"M6 18L18 6M6 6l12 12\" \/>\r\n        <\/svg>\r\n        <iframe loading=\"lazy\" id=\"payment-secure-iframe\" src=\"\" title=\"Pago seguro\" width=\"100%\" height=\"100%\">\r\n        <\/iframe>\r\n    <\/div>\r\n<\/div>\r\n\r\n<form id=\"individual-form\" class=\"form-main\" style=\"display : none;\" data-mirror=\"3\" action=\"\">\r\n    <div id=\"payment-component\" class=\"modal-acquired\">\r\n        <!-- <svg onclick=\"document.getElementById('payment-form').style.display = 'none';\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" fill=\"none\" viewBox=\"0 0 24 24\" stroke-width=\"1.5\" stroke=\"currentColor\" class=\"close-icon\">\r\n            <path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"M6 18L18 6M6 6l12 12\" \/>\r\n        <\/svg> -->\r\n\r\n        <div class=\"modal-acquired-content\">\r\n\r\n            <div class=\"header\">\r\n                <h1 id=\"hipay-modal-title\" class=\"title v2\">Acceda a su an\u00e1lisis completo<\/h1>\r\n                <p id=\"hipay-modal-subtitle\" class=\"subtitle\">\r\n                    Descubra sus resultados detallados por dimensi\u00f3n de personalidad.<br>\r\n                    A continuaci\u00f3n, cargue su perfil completo en un solo clic.\r\n                <\/p>\r\n\r\n            <\/div>\r\n\r\n\r\n            <div class=\"content\">\r\n                <div class=\"guarantee-badge\">Satisfecho o le devolvemos su dinero<\/div>\r\n                <div class=\"step-1\">\r\n                    <!-- <div class=\"flex-input\">\r\n\r\n                    <\/div> -->\r\n\r\n                    <div class=\"input-container\" style=\"width : 100%; margin-bottom:0px !important;\">\r\n                        <label id=\"hipay-card-holder-label\" for=\"hipay-card-holder\">Nombre y apellidos<\/label>\r\n                        <div id=\"hipay-card-holder\" class=\"form-control hostedfield\"><\/div>\r\n                        <p class=\"component-error\"><\/p>\r\n                    <\/div>\r\n                    <div class=\"input-container cc-mail\" style=\"display: flex;width : 100%;flex-direction: column;\">\r\n                        <label id=\"hipay-mail-holder-label\" for=\"hipay-mail-holder\">Direcci\u00f3n de correo electr\u00f3nico<\/label>\r\n                        <input\r\n                            required\r\n id=\"hipay-mail-holder\"\r\n                            class=\"form-control hostedfield focus-visible-only\"\r\n                            name=\"email\"\r\n                            type=\"email\"\r\n                            maxlength=\"80\"\r\n                            title=\"Direcci\u00f3n de correo electr\u00f3nico v\u00e1lida\" \/>\r\n\r\n                    <\/div>\r\n\r\n                    <div class=\"input-container country-selector\">\r\n                        <label id=\"hipay-address-holder-label\" for=\"hipay-adress-holder\">Pa\u00eds<\/label>\r\n                        <!-- <input required id=\"hipay-address-holder\" \r\n                            class=\"form-control hostedfield focus-visible-only\"><\/input> -->\r\n                        <!-- SELECT EUROPE COUNTRY-->\r\n                        <label class=\"select\" for=\"hipay-address-holder\"><select id=\"hipay-address-holder\"\r\n                                class=\"form-control hostedfield focus-visible-only\" required=\"required\">\r\n                                <option value=\"FR\" selected=\"selected\">Francia<\/option>\r\n                                <option value=\"AL\">Albania<\/option>\r\n                                <option value=\"DE\">Alemania<\/option>\r\n                                <option value=\"AD\">Andorra<\/option>\r\n                                <option value=\"AT\">Austria<\/option>\r\n                                <option value=\"BE\">B\u00e9lgica<\/option>\r\n                                <option value=\"BY\">Bielorrusia<\/option>\r\n                                <option value=\"BA\">Bosnia-Herzegovina<\/option>\r\n                                <option value=\"BG\">Bulgaria<\/option>\r\n                                <option value=\"HR\">Croacia<\/option>\r\n                                <option value=\"DK\">Dinamarca<\/option>\r\n                                <option value=\"ES\">Espa\u00f1a<\/option>\r\n                                <option value=\"EE\">Estonia<\/option>\r\n                                <option value=\"FI\">Finlandia<\/option>\r\n                                <option value=\"GR\">Grecia<\/option>\r\n                                <option value=\"HU\">Hungr\u00eda<\/option>\r\n                                <option value=\"IE\">Irlanda<\/option>\r\n                                <option value=\"IS\">Islandia<\/option>\r\n                                <option value=\"IT\">Italia<\/option>\r\n                                <option value=\"XK\">Kosovo<\/option>\r\n                                <option value=\"LV\">Letonia<\/option>\r\n                                <option value=\"LI\">Liechtenstein<\/option>\r\n                                <option value=\"LT\">Lituania<\/option>\r\n                                <option value=\"LU\">Luxemburgo<\/option>\r\n                                <option value=\"MK\">Macedonia del Norte<\/option>\r\n                                <option value=\"MT\">Malta<\/option>\r\n                                <option value=\"MD\">Moldavia<\/option>\r\n                                <option value=\"MC\">M\u00f3naco<\/option>\r\n                                <option value=\"ME\">Montenegro<\/option>\r\n                                <option value=\"NO\">Noruega<\/option>\r\n                                <option value=\"NL\">Pa\u00edses Bajos<\/option>\r\n                                <option value=\"PL\">Polonia<\/option>\r\n                                <option value=\"PT\">Portugal<\/option>\r\n                                <option value=\"RO\">Ruman\u00eda<\/option>\r\n                                <option value=\"RU\">Rusia<\/option>\r\n                                <option value=\"SM\">San Marino<\/option>\r\n                                <option value=\"RS\">Serbia<\/option>\r\n                                <option value=\"SK\">Eslovaquia<\/option>\r\n                                <option value=\"SI\">Eslovenia<\/option>\r\n                                <option value=\"SE\">Suecia<\/option>\r\n                                <option value=\"CH\">Suiza<\/option>\r\n                                <option value=\"CZ\">Rep\u00fablica Checa<\/option>\r\n                                <option value=\"UA\">Ucrania<\/option>\r\n                                <option value=\"GB\">Reino Unido<\/option>\r\n                                <option value=\"VA\">Vaticano<\/option>\r\n                            <\/select>\r\n                            <svg>\r\n                                <use xlink:href=\"#select-arrow-down\"><\/use>\r\n                            <\/svg><\/label>\r\n                        <!-- SVG Sprites--><svg class=\"sprites\">\r\n                            <symbol id=\"select-arrow-down\" viewbox=\"0 0 10 6\">\r\n                                <polyline points=\"1 1 5 5 9 1\"><\/polyline>\r\n                            <\/symbol>\r\n                        <\/svg>\r\n\r\n\r\n                    <\/div>\r\n                    <p id=\"card-errors\" class=\"alert-danger\" role=\"alert\"><\/p>\r\n                    <div class=\"bottom-content\">\r\n\r\n                        <label class=\"checkbox-container\" for=\"cgu\">\r\n                            <input type=\"checkbox\" id=\"cgu\" name=\"cgu\" style=\"opacity: 0;position: absolute;\" \/>\r\n                            <div class=\"checkbox\"><span class=\"checkmark\"><\/span><\/div>\r\n                            <p id=\"checkbox-label\" class=\"text\">He le\u00eddo y acepto el <a\r\n                                    href=\"https:\/\/psona.io\/es\/termes-et-conditions\/\" target=\"_blank\">CONDICIONES GENERALES<\/a>, <a\r\n                                    href=\"https:\/\/psona.io\/es\/politique-de-confidentialite\/\">RGPD Privacidad<\/a>, <a\r\n                                    href=\"https:\/\/psona.io\/es\/mentions-legales\/\">Datos RGPD<\/a> y <a\r\n                                    href=\"https:\/\/psona.io\/es\/conditions-de-paiement-recurrent\/\">RCP<\/a>confidencialidad\r\n                                La confidencialidad de los datos se respeta estrictamente mediante\r\n                                medidas vigentes del RGPD y se suprimen peri\u00f3dicamente.<\/p>\r\n                        <\/label>\r\n\r\n                    <\/div>\r\n                    <button type=\"button\" id=\"continueButton\" class=\"simpay-next-step\">\ud83d\udd12 Desbloquea tu perfil completo<i\r\n                            class=\"fa-solid fa-arrow-right\" style=\"color: #ffffff;float:right;\"><\/i><\/button>\r\n                    <p class=\"cta-note\">\u2714 Acceso garantizado en segundos - Oferta de 0,50 euros hoy<\/p>\r\n                    <div class=\"secure-payment\">\r\n                        <div class=\"img-wrap\"><img decoding=\"async\"\r\n                                src=\"https:\/\/psona.io\/wp-content\/uploads\/2024\/09\/shield-halved-solid-1.svg\"\r\n                                alt=\"secure-payment\"><\/div>\r\n                        <div class=\"text-wrap\">\r\n                            <p>Todas las transacciones son seguras y est\u00e1n encriptadas. La informaci\u00f3n de las tarjetas de cr\u00e9dito\r\n                                nunca se almacena en el sitio.<\/p>\r\n                        <\/div>\r\n                    <\/div>\r\n                    <p id=\"cgu-text-modal-hipay\" class=\"cgu-text-modal-hipay\">\r\n                        CLICKBUSTER LTD63-66 Hatton Garden , EC1N 8LE, London Bank description psona.io.\r\n                        Al hacer clic en \"Obtener mis resultados\", confirma que ha le\u00eddo y aceptado los siguientes t\u00e9rminos y condiciones. <a\r\n                            href='https:\/\/psona.io\/es\/termes-et-conditions\/'>Condiciones generales\r\n                            Condiciones generales<\/a>. El test de personalidad tiene un coste de 0,50 euros durante un\r\n                        periodo de prueba\r\n                        per\u00edodo de prueba de 24\r\n                        de prueba. Una vez transcurrido el per\u00edodo de prueba de 24 horas y sin cancelaci\u00f3n por su parte,\r\n                        nuestra\r\n                        oferta se ampliar\u00e1 autom\u00e1ticamente a una suscripci\u00f3n no vinculante a un precio de\r\n                        47,5 \u20ac\r\n                        por\r\n                        mes. Encontrar\u00e1 m\u00e1s informaci\u00f3n en nuestra lista de precios. Puede cancelar su\r\n                        suscripci\u00f3n\r\n                        en <a href=\"https:\/\/psona.io\/es\/se-desabonner\/\">esta p\u00e1gina<\/a> y consulte las\r\n                        condiciones de los pagos peri\u00f3dicos de <a\r\n                            href=\"https:\/\/psona.io\/es\/conditions-de-paiement-recurrent\/\">esta\r\n                            p\u00e1gina<\/a>.<\/p>\r\n\r\n                <\/div>\r\n                <div class=\"step-2\">\r\n                    <div class=\"offers-container\">\r\n                        <!-- Offre Basic -->\r\n                        <div class=\"offer selected\" data-offer=\"basic\" onclick=\"selectOffer(this, '0.50')\">\r\n                            <div class=\"radio-button\"><\/div>\r\n                            <div class=\"offer-header\">\r\n                                <div class=\"offer-left\">\r\n                                    <div class=\"offer-title\">An\u00e1lisis completo<\/div>\r\n                                    <div class=\"offer-price\">\r\n                                        <span class=\"current-price\">0,50 \u20ac<\/span>\r\n                                    <\/div>\r\n                                    <div class=\"offer-description\">\r\n                                        Acceso inmediato a todos sus resultados\r\n                                    <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <!-- Offre Premium -->\r\n                        <div class=\"offer\" data-offer=\"premium\" onclick=\"selectOffer(this, '9.99')\">\r\n                            <div class=\"popular-badge\">Popular<\/div>\r\n                            <div class=\"radio-button\"><\/div>\r\n                            <div class=\"offer-header\">\r\n                                <div class=\"offer-left\">\r\n                                    <div class=\"offer-title\">An\u00e1lisis + eBook<\/div>\r\n                                    <div class=\"offer-price\">\r\n                                        <span class=\"current-price\">9,99 \u20ac<\/span>\r\n                                        <span class=\"original-price\">29,90 \u20ac<\/span>\r\n                                    <\/div>\r\n                                    <div class=\"offer-description\">\r\n                                        Todos sus resultados + gu\u00eda de desarrollo personal\r\n                                    <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                            <div class=\"ebook-preview\">\r\n                                <img decoding=\"async\" src=\"https:\/\/psona.io\/wp-content\/uploads\/2025\/09\/ebook_cover.png\" alt=\"Guide de d\u00e9veloppement personnel\" class=\"ebook-cover\">\r\n\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                    <div class=\"split-input\">\r\n\r\n                        <div class=\"input-container cc-number\">\r\n                            <label id=\"hipay-card-number-label\" for=\"hipay-card-number\">Tarjeta de cr\u00e9dito<\/label>\r\n                            <div id=\"hipay-card-number\" class=\"hostedfield form-control\"><\/div>\r\n                        <\/div>\r\n\r\n                        <div class=\"input-container cc-exp\">\r\n                            <label id=\"hipay-expiry-date-label\" for=\"hipay-expiry-date\">Fecha de caducidad<\/label>\r\n                            <div id=\"hipay-expiry-date\" class=\"hostedfield form-control\"><\/div>\r\n                        <\/div>\r\n\r\n                        <div class=\"input-container cc-cvc\">\r\n                            <label id=\"hipay-cvc-label\" for=\"hipay-cvc\">C\u00f3digo de seguridad<\/label>\r\n                            <div id=\"hipay-cvc\" class=\"form-control hostedfield\"><\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n                    <div class=\"hipay-checkout-container\">\r\n                        <!-- <button type=\"button\" class=\"simpay-previous-step\" id=\"previous-btn\"><i class=\"fa-solid fa-arrow-left\" style=\"color: #ffffff;float:left;\"><\/i>\r\n                            Pr\u00e9c\u00e9dent<\/button> -->\r\n                        <button type=\"submit\" id=\"send-payment\" class=\"payment-button\">\ud83d\udd12 Obtener mis resultados<\/button>\r\n                        <img decoding=\"async\" src=\"https:\/\/psona.io\/wp-content\/uploads\/2024\/09\/ReassuranceLogo.svg\"\r\n                            alt=\"reassurance-logo\" \/>\r\n                    <\/div>\r\n                    <div class=\"reassurance\">\r\n                        <div class=\"badge badge-pay\">\r\n                            \ud83d\udd12 <span>100% pago seguro<\/span>\r\n                        <\/div>\r\n                        <div class=\"badge badge-users\">\r\n                            \ud83d\udcc8 <span>+2.000 usuarios este mes<\/span>\r\n                        <\/div>\r\n                        <div class=\"badge badge-support\">\r\n                            \ud83d\udcac <span>Ayuda 7\/7<\/span>\r\n                        <\/div>\r\n                    <\/div>\r\n                    <p id=\"cgu-text-modal-hipay\" class=\"cgu-text-modal-hipay\" style=\"font-size:14px !important;\">\r\n                        CLICKBUSTER LTD63-66 Hatton Garden , EC1N 8LE, Londres <br>\r\n                        <strong>El descriptor aparecer\u00e1 en su extracto bancario como :<\/strong> psona.io<br><br>\r\n\r\n                        En cliquant sur \"Obtenir mes r\u00e9sultats\", vous confirmez avoir lu et accept\u00e9 les <a\r\n                            href='https:\/\/psona.io\/es\/termes-et-conditions\/'>Condiciones generales\r\n                            Condiciones generales<\/a>. El test de personalidad tiene un coste de 0,50 euros durante un\r\n                        periodo de prueba\r\n                        per\u00edodo de prueba de 24\r\n                        de prueba. Una vez transcurrido el per\u00edodo de prueba de 24 horas y sin cancelaci\u00f3n por su parte,\r\n                        nuestra\r\n                        oferta se ampliar\u00e1 autom\u00e1ticamente a una suscripci\u00f3n no vinculante a un precio de\r\n                        47,5 \u20ac\r\n                        por\r\n                        mes. Encontrar\u00e1 m\u00e1s informaci\u00f3n en nuestra lista de precios. Puede cancelar su\r\n                        suscripci\u00f3n\r\n                        en <a href=\"https:\/\/psona.io\/es\/se-desabonner\/\">esta p\u00e1gina<\/a> y consulte las\r\n                        condiciones de los pagos peri\u00f3dicos de <a\r\n                            href=\"https:\/\/psona.io\/es\/conditions-de-paiement-recurrent\/\">esta\r\n                            p\u00e1gina<\/a>.\r\n                    <\/p>\r\n                <\/div>\r\n\r\n                <input type=\"hidden\" id=\"ioBB\" name=\"hipay-fingerprint\" \/>\r\n\r\n            <\/div>\r\n            <footer class=\"footer\">\r\n            <\/footer>\r\n        <\/div>\r\n    <\/div>\r\n    <\/div>\r\n<input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form>\r\n\r\n<script>\r\n    function selectOffer(offerElement, price) {\r\n        \/\/ Retirer la s\u00e9lection de toutes les offres\r\n        document.querySelectorAll('.offer').forEach(offer => {\r\n            offer.classList.remove('selected');\r\n        });\r\n\r\n        \/\/ S\u00e9lectionner l'offre cliqu\u00e9e\r\n        offerElement.classList.add('selected');\r\n\r\n        \/\/ \/\/ Mettre \u00e0 jour le bouton de paiement\r\n        \/\/ const button = document.getElementById('send-payment');\r\n        \/\/ if (price === '0.50') {\r\n        \/\/     button.textContent = '\ud83d\udd12 Obtenir mes r\u00e9sultats - 0,50 \u20ac';\r\n        \/\/ } else {\r\n        \/\/     button.textContent = '\ud83d\udd12 Obtenir mes r\u00e9sultats - 9,99 \u20ac';\r\n        \/\/ }\r\n    }\r\n<\/script>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; admin_label=&#8221;Loading results&#8230;&#8221; module_id=&#8221;custom-loading&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_enable_image=&#8221;off&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;center_right&#8221; background_horizontal_offset=&#8221;0%&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;0px|50px|50px|50px|false|true&#8221; custom_padding_tablet=&#8221;0px|50px|50px|50px|false|true&#8221; custom_padding_phone=&#8221;|30px||30px|true|true&#8221; background_last_edited=&#8221;off|desktop&#8221; background_size_tablet=&#8221;cover&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_enable_image=&#8221;off&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; height=&#8221;100%&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; custom_css_before=&#8221;  &#8221; global_colors_info=&#8221;{}&#8221; custom_css_before_last_edited=&#8221;off|desktop&#8221; custom_css_before_tablet=&#8221;  &#8221; custom_css_before_phone=&#8221;  &#8220;][et_pb_column type=&#8221;1_2&#8243; module_class=&#8221;stats-column&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_enable_image=&#8221;off&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;center_right&#8221; custom_padding=&#8221;50px||||false|false&#8221; custom_padding_tablet=&#8221;0px||||false|false&#8221; custom_padding_phone=&#8221;30px||||false|false&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221; custom_css_before_last_edited=&#8221;off|desktop&#8221; custom_css_before_tablet=&#8221;    content: %22%22;||    background: url(https:\/\/psona.io\/wp-content\/uploads\/2024\/10\/BG_Tab.svg);||    height: 1400px;||    width: 1400px;||    position: absolute;||    background-repeat: no-repeat;||    background-size: 100%;||    background-position: center;||    top: -400px;||    left: -280px;||    z-index: -1;&#8221; custom_css_before_phone=&#8221;content: %22%22;||    background: url(https:\/\/psona.io\/wp-content\/uploads\/2024\/10\/BG_Tab.svg);||    height: 900px;||    width: 900px;||    position: absolute;||    background-repeat: no-repeat;||    background-size: cover;||    background-position: center;||    top: -380px;||    left: -280px;||    z-index: -1;&#8221;][et_pb_code _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<div class=\"card preview-card\"><!-- [et_pb_line_break_holder] -->  <\/p>\n<div class=\"chip\">Resumen de su informe<\/div>\n<p><!-- [et_pb_line_break_holder] -->  <\/p>\n<h1>Vos r\u00e9sultats sont disponibles<\/h1>\n<p><!-- [et_pb_line_break_holder] --> <pee class=\"intro\">Acc\u00e9dez \u00e0 votre profil indicatif gr\u00e2ce \u00e0 notre p\u00e9riode d&#8217;essai de 24 heures.<\/pee> <!-- [et_pb_line_break_holder] -->  <\/p>\n<div class=\"score-preview\"><!-- [et_pb_line_break_holder] -->    <\/p>\n<div class=\"total-score\"><!-- [et_pb_line_break_holder] -->      <\/p>\n<div class=\"hidden-score blur-score\">Lorem ipsum<\/div>\n<p><!-- [et_pb_line_break_holder] -->      <\/p>\n<div class=\"hidden-level blur-score\">Tu perfil<\/div>\n<p><!-- [et_pb_line_break_holder] -->    <\/div>\n<p><!-- [et_pb_line_break_holder] -->    <\/p>\n<div class=\"category-scores\"><!-- [et_pb_line_break_holder] -->      <\/p>\n<div class=\"category\"><!-- [et_pb_line_break_holder] -->        <span class=\"cat-name\">Tu perfil<\/span><!-- [et_pb_line_break_holder] -->        <span class=\"cat-score blur-score\">Muy fuerte<\/span><!-- [et_pb_line_break_holder] -->      <\/div>\n<p><!-- [et_pb_line_break_holder] -->      <\/p>\n<div class=\"category\"><!-- [et_pb_line_break_holder] -->        <span class=\"cat-name\">Extraversion, Stabilit\u00e9 \u00e9motionnelle, Sens des responsabilit\u00e9s<\/span><!-- [et_pb_line_break_holder] -->        <span class=\"cat-score blur-score\">Bajo<\/span><!-- [et_pb_line_break_holder] -->      <\/div>\n<p><!-- [et_pb_line_break_holder] -->        <\/p>\n<div class=\"category\"><!-- [et_pb_line_break_holder] -->        <span class=\"cat-name\">Ouverture d&#8217;esprit, Sociabilit\u00e9<\/span><!-- [et_pb_line_break_holder] -->        <span class=\"cat-score blur-score\">Bajo<\/span><!-- [et_pb_line_break_holder] -->      <\/div>\n<p><!-- [et_pb_line_break_holder] -->      <!-- [et_pb_line_break_holder] -->    <\/div>\n<p><!-- [et_pb_line_break_holder] -->  <\/div>\n<p><!-- [et_pb_line_break_holder] -->  <\/p>\n<div class=\"unlock-text\">\ud83d\udd12 Acc\u00e9dez \u00e0 vos r\u00e9sultats \u2014 Essai 0,50 \u20ac (24h)<\/div>\n<p><!-- [et_pb_line_break_holder] --> <\/p>\n<div class=\"unlock-cta\">\ud83d\udd12 Acc\u00e9der \u00e0 mes r\u00e9sultats<\/div>\n<p><!-- [et_pb_line_break_holder] -->  <\/p>\n<div class=\"features-inline\"><!-- [et_pb_line_break_holder] --><\/p>\n<div class=\"feature\">\u2705 R\u00e9sultats pr\u00e9sent\u00e9s par dimension<\/div>\n<p><!-- [et_pb_line_break_holder] --><\/p>\n<div class=\"feature\">\ud83d\udcca Profil d\u00e9taill\u00e9 selon les 5 facteurs<\/div>\n<p><!-- [et_pb_line_break_holder] --><\/p>\n<div class=\"feature\">\ud83d\udd04 Acc\u00e8s illimit\u00e9 aux questionnaires<\/div>\n<p><!-- [et_pb_line_break_holder] --><\/div>\n<p><!-- [et_pb_line_break_holder] --><\/div>\n<p>[\/et_pb_code][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; module_id=&#8221;col-payment&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;50px||0px|100px|false|false&#8221; custom_padding_tablet=&#8221;|||0px|false|false&#8221; custom_padding_phone=&#8221;80px||0px||false|false&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code module_id=&#8221;hipay-test&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>","protected":false},"excerpt":{"rendered":"<p>Test de personnalit\u00e9Votre personnalit\u00e9 est aussi unique que vous. Vivez une exp\u00e9rience introspective captivante en r\u00e9alisant notre test de personnalit\u00e9 exclusif.-10 minutes Notre test prend moinsde 10 minutesHonn\u00eatet\u00e9 Vous devez r\u00e9pondre honn\u00eatement (m\u00eame si vous n&#8217;aimez pas les r\u00e9ponses).Pas de neutre Essayez de ne pas laisser de r\u00e9ponse neutres. -10 minutes Notre test prend moins [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:divi\/placeholder \/-->","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"class_list":["post-48","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/psona.io\/es\/wp-json\/wp\/v2\/pages\/48","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/psona.io\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/psona.io\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/psona.io\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/psona.io\/es\/wp-json\/wp\/v2\/comments?post=48"}],"version-history":[{"count":45,"href":"https:\/\/psona.io\/es\/wp-json\/wp\/v2\/pages\/48\/revisions"}],"predecessor-version":[{"id":2627,"href":"https:\/\/psona.io\/es\/wp-json\/wp\/v2\/pages\/48\/revisions\/2627"}],"wp:attachment":[{"href":"https:\/\/psona.io\/es\/wp-json\/wp\/v2\/media?parent=48"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}